{"id":1927,"date":"2023-09-09T10:19:16","date_gmt":"2023-09-09T10:19:16","guid":{"rendered":"https:\/\/dev-nbc-ev.pantheonsite.io\/?page_id=1927"},"modified":"2025-08-05T20:08:31","modified_gmt":"2025-08-05T18:08:31","slug":"u11-district-league","status":"publish","type":"page","link":"https:\/\/nbc-ev.de\/en\/u11-district-league\/","title":{"rendered":"U10mix-Kreisliga"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"1927\" class=\"elementor elementor-1927\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-78e76764fe308 elementor-section-content-bottom elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"78e76764fe308\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-db50270\" data-id=\"db50270\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1acc524 e-transform elementor-widget elementor-widget-heading\" data-id=\"1acc524\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">U10mix Kreisliga<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-162daf4996b23 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"162daf4996b23\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4b8a688\" data-id=\"4b8a688\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4f8e73e elementor-widget elementor-widget-image\" data-id=\"4f8e73e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"960\" height=\"150\" src=\"https:\/\/nbc-ev.de\/wp-content\/uploads\/2023\/09\/Ads-1024x160.png\" class=\"attachment-large size-large wp-image-3782\" alt=\"\" srcset=\"https:\/\/nbc-ev.de\/wp-content\/uploads\/2023\/09\/Ads-1024x160.png 1024w, https:\/\/nbc-ev.de\/wp-content\/uploads\/2023\/09\/Ads-300x47.png 300w, https:\/\/nbc-ev.de\/wp-content\/uploads\/2023\/09\/Ads-768x120.png 768w, https:\/\/nbc-ev.de\/wp-content\/uploads\/2023\/09\/Ads-1536x240.png 1536w, https:\/\/nbc-ev.de\/wp-content\/uploads\/2023\/09\/Ads.png 2048w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4aec6f64 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"4aec6f64\" data-element_type=\"section\" data-e-type=\"section\" id=\"xs_team_7\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-46f269b2\" data-id=\"46f269b2\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1d3557c2 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"1d3557c2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-1735869f\" data-id=\"1735869f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-123e2203 elementor-widget__width-initial elementor-widget elementor-widget-elementskit-heading\" data-id=\"123e2203\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper center   ekit_heading_tablet-   ekit_heading_mobile-\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ebce040 elementor-widget elementor-widget-elementskit-team\" data-id=\"1ebce040\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-team.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\">\t\t\t\t\t\t\t\t <div class=\"profile-square-v square-v6 square-v6-v2 no_gutters\">\n\t\t<div class=\"profile-card elementor-animation- text-center ekit-team-style-long_height_details_hover\">\n\t\t\t\t\t\t\t<a aria-label=\"profile\" href=\"javascript:void(0)\" data-mfp-src=\"#ekit_team_modal_1ebce040_1927\" class=\"ekit-team-popup\">\n\t\t\t\n\t\t\t\t<div class=\"profile-header ekit-team-img\"  data-toggle=\"modal\" data-target=\"ekit_team_modal_#1ebce040_1927\" >\n\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/nbc-ev.de\/wp-content\/uploads\/2023\/10\/mike.png\" class=\"attachment-large size-large wp-image-4477\" alt=\"\" srcset=\"https:\/\/nbc-ev.de\/wp-content\/uploads\/2023\/10\/mike.png 800w, https:\/\/nbc-ev.de\/wp-content\/uploads\/2023\/10\/mike-300x300.png 300w, https:\/\/nbc-ev.de\/wp-content\/uploads\/2023\/10\/mike-150x150.png 150w, https:\/\/nbc-ev.de\/wp-content\/uploads\/2023\/10\/mike-768x768.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t<\/div><!-- .profile-header END -->\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\n\n\t\t\t\t<div class=\"profile-body\">\n\t\t\t\t\t\n\t\t\t\t\t<h2 class=\"profile-title\">\n\t\t\t\t\t\t\t\t\t\t\t<a aria-label=\"profile\" href=\"javascript:void(0)\" data-mfp-src=\"#ekit_team_modal_1ebce040_1927\" class=\"ekit-team-popup\">\n\t\t\t\t\t\tMike\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t<p class=\"profile-designation\">Trainer<\/p>\n\t\t\t\t\t\t\t\t\t<\/div><!-- .profile-body END -->\n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t <\/div> \t\t\t\n\t\t\t\n\t\t\t\t\t<div class=\"zoom-anim-dialog mfp-hide elementskit-team-popup team-popup-id-1ebce040\" id=\"ekit_team_modal_1ebce040_1927\" tabindex=\"-1\" role=\"dialog\" aria-modal=\"true\">\n\t\t\t\t<div class=\"modal-dialog modal-dialog-centered\" role=\"document\">\n\t\t\t\t\t<div class=\"modal-content\">\n\t\t\t\t\t\t<button type=\"button\" class=\"ekit-team-modal-close\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-times\"><\/i>\t\t\t\t\t\t<\/button>\n\n\t\t\t\t\t\t<div class=\"modal-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ekit-team-modal-img\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/nbc-ev.de\/wp-content\/uploads\/2023\/10\/mike.png\" class=\"attachment-large size-large wp-image-4477\" alt=\"\" srcset=\"https:\/\/nbc-ev.de\/wp-content\/uploads\/2023\/10\/mike.png 800w, https:\/\/nbc-ev.de\/wp-content\/uploads\/2023\/10\/mike-300x300.png 300w, https:\/\/nbc-ev.de\/wp-content\/uploads\/2023\/10\/mike-150x150.png 150w, https:\/\/nbc-ev.de\/wp-content\/uploads\/2023\/10\/mike-768x768.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"ekit-team-modal-info has-img\">\n\t\t\t\t\t\t\t\t<h2 class=\"ekit-team-modal-title\">Mike<\/h2>\n\t\t\t\t\t\t\t\t<p class=\"ekit-team-modal-position\">Trainer<\/p>\n\n\t\t\t\t\t\t\t\t<div class=\"ekit-team-modal-content\">\n\t\t\t\t\t\t\t\t\t1980 Erwerb der Trainerlizenz f\u00fcr Basketball C-Leistungssport und regelm\u00e4\u00dfig Fortbildungen besucht, um die Lizenz und das Trainerwissen aktuell zu halten. Bereits 1979 die Ausbildung f\u00fcr die Schiedsrichterlizenz (LSD) absolviert.\nAnfangs noch als aktiver Spieler und Spielertrainer eingesetzt und sp\u00e4ter dann ohne Unterbrechung als Trainer f\u00fcr Herren und Damen sowie im gesamten Jugendbereich t\u00e4tig.\nIn den letzten Jahren nur noch im Jugendbereich engagiert und einige Bayerische Meistertitel errungen. Viele Jugendcamps f\u00fcr den Bayerischen Basketballverband geleitet und auch einige Spieler entwickelt, die es bis in die Bundesliga und auch Nationalmannschaft geschafft haben.\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<ul class=\"ekit-team-modal-list\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><strong>Phone:<\/strong><a href=\"tel:+49 1607961423\">+49 1607961423<\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><strong>Email:<\/strong><a href=\"mailto:mike@nbc-ev.de\">mike@nbc-ev.de<\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-d8d0b1f\" data-id=\"d8d0b1f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-66f91a5 wpr-logo-position-center elementor-widget elementor-widget-wpr-logo\" data-id=\"66f91a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wpr-logo.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\n\t\t\t<div class=\"wpr-logo elementor-clearfix\">\n\n\t\t\t\t\t\t\t\t<picture class=\"wpr-logo-image\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/nbc-ev.de\/wp-content\/uploads\/2022\/03\/nbc_logo_w.png\" alt=\"\">\n\n\t\t\t\t\t\t\t\t\t<\/picture>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-4b45c44\" data-id=\"4b45c44\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b42298a elementor-widget elementor-widget-elementskit-team\" data-id=\"b42298a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-team.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\">\t\t\t\t\t\t\t\t <div class=\"profile-square-v square-v6 square-v6-v2 no_gutters\">\n\t\t<div class=\"profile-card elementor-animation- text-center ekit-team-style-long_height_details_hover\">\n\t\t\t\t\t\t\t<a aria-label=\"profile\" href=\"javascript:void(0)\" data-mfp-src=\"#ekit_team_modal_b42298a_1927\" class=\"ekit-team-popup\">\n\t\t\t\n\t\t\t\t<div class=\"profile-header ekit-team-img\"  data-toggle=\"modal\" data-target=\"ekit_team_modal_#b42298a_1927\" >\n\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/nbc-ev.de\/wp-content\/uploads\/2023\/10\/Blue-Professional-Linkedin-Profile-Picturehjj.png\" class=\"attachment-large size-large wp-image-4473\" alt=\"\" srcset=\"https:\/\/nbc-ev.de\/wp-content\/uploads\/2023\/10\/Blue-Professional-Linkedin-Profile-Picturehjj.png 800w, https:\/\/nbc-ev.de\/wp-content\/uploads\/2023\/10\/Blue-Professional-Linkedin-Profile-Picturehjj-300x300.png 300w, https:\/\/nbc-ev.de\/wp-content\/uploads\/2023\/10\/Blue-Professional-Linkedin-Profile-Picturehjj-150x150.png 150w, https:\/\/nbc-ev.de\/wp-content\/uploads\/2023\/10\/Blue-Professional-Linkedin-Profile-Picturehjj-768x768.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t<\/div><!-- .profile-header END -->\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\n\n\t\t\t\t<div class=\"profile-body\">\n\t\t\t\t\t\n\t\t\t\t\t<h2 class=\"profile-title\">\n\t\t\t\t\t\t\t\t\t\t\t<a aria-label=\"profile\" href=\"javascript:void(0)\" data-mfp-src=\"#ekit_team_modal_b42298a_1927\" class=\"ekit-team-popup\">\n\t\t\t\t\t\tMartina\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t<p class=\"profile-designation\">Trainerin<\/p>\n\t\t\t\t\t\t\t\t\t<\/div><!-- .profile-body END -->\n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t <\/div> \t\t\t\n\t\t\t\n\t\t\t\t\t<div class=\"zoom-anim-dialog mfp-hide elementskit-team-popup team-popup-id-b42298a\" id=\"ekit_team_modal_b42298a_1927\" tabindex=\"-1\" role=\"dialog\" aria-modal=\"true\">\n\t\t\t\t<div class=\"modal-dialog modal-dialog-centered\" role=\"document\">\n\t\t\t\t\t<div class=\"modal-content\">\n\t\t\t\t\t\t<button type=\"button\" class=\"ekit-team-modal-close\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-times\"><\/i>\t\t\t\t\t\t<\/button>\n\n\t\t\t\t\t\t<div class=\"modal-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ekit-team-modal-img\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/nbc-ev.de\/wp-content\/uploads\/2023\/10\/Blue-Professional-Linkedin-Profile-Picturehjj.png\" class=\"attachment-large size-large wp-image-4473\" alt=\"\" srcset=\"https:\/\/nbc-ev.de\/wp-content\/uploads\/2023\/10\/Blue-Professional-Linkedin-Profile-Picturehjj.png 800w, https:\/\/nbc-ev.de\/wp-content\/uploads\/2023\/10\/Blue-Professional-Linkedin-Profile-Picturehjj-300x300.png 300w, https:\/\/nbc-ev.de\/wp-content\/uploads\/2023\/10\/Blue-Professional-Linkedin-Profile-Picturehjj-150x150.png 150w, https:\/\/nbc-ev.de\/wp-content\/uploads\/2023\/10\/Blue-Professional-Linkedin-Profile-Picturehjj-768x768.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"ekit-team-modal-info has-img\">\n\t\t\t\t\t\t\t\t<h2 class=\"ekit-team-modal-title\">Martina<\/h2>\n\t\t\t\t\t\t\t\t<p class=\"ekit-team-modal-position\">Trainerin<\/p>\n\n\t\t\t\t\t\t\t\t<div class=\"ekit-team-modal-content\">\n\t\t\t\t\t\t\t\t\tNach einer aktiven und erfolgreichen Spielerkarriere  bin ich seit vielen Jahren als Trainerin (C-Leistungstrainerin\/ \u00dcbungsleiterin seit 2000) ehrenamtlich t\u00e4tig, seit 2017 beim NBC. \nDes Weiteren habe ich langj\u00e4hrige Erfahrung als Schiedsrichterin (C-Lizenz). \nMein Interesse gilt vor allem dem Jugendbereich, Anfangs trainierte ich ein U16 weiblich-Team, danach widmete ich mich \u2013bis auf zwei Saisons mit einem U14-Team -fast ausschlie\u00dflich der Altersklasse U12 (also 11Jahre und j\u00fcnger), da hier meiner Meinung nach der \u201eGrundstein\u201c gelegt wird, menschlich, sozial und auch spielerisch-spieltechnisch. Kinder f\u00fcr diesen tollen Sport zu begeistern und sich mit Freude und Spa\u00df weiter zu entwickeln, steht hierbei f\u00fcr mich im Vordergrund.\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<ul class=\"ekit-team-modal-list\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><strong>Phone:<\/strong><a href=\"tel:+491577 3951388\">+491577 3951388<\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><strong>Email:<\/strong><a href=\"mailto:martina@nbc-ev.de\">martina@nbc-ev.de<\/a><\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-71bd373 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"71bd373\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5562144\" data-id=\"5562144\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-729628a elementor-section-full_width elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"729628a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-389e523\" data-id=\"389e523\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e688175 elementor-widget elementor-widget-heading\" data-id=\"e688175\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">U10 Ausbildungszeiten<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d167481 elementor-widget elementor-widget-text-editor\" data-id=\"d167481\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>In den H\u00e4nden von engagierten U10-Trainern bei NBC eV werden diese jungen Spielerinnen und Spieler zu den zuk\u00fcnftigen S\u00e4ulen des Basketballs geformt<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-3252e60 elementor-hidden-tablet\" data-id=\"3252e60\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-5c5da37\" data-id=\"5c5da37\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f2f4013 elementor-widget elementor-widget-heading\" data-id=\"f2f4013\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Training times<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1657f17 elementor-widget elementor-widget-elementskit-heading\" data-id=\"1657f17\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_center   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--title elementskit-section-title\">DIENSTAGS UND DONNERSTAGS<\/h2>\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p><strong>TIME :<\/strong> 16:00 - 18:00<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f7678c2 elementor-widget elementor-widget-elementskit-heading\" data-id=\"f7678c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_center   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--title elementskit-section-title\">HALL<\/h2>\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p>D\u00fcrer Gymnasium,Sielstr. 17, 90429 Nuremberg<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7014f45 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"7014f45\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-91db887\" data-id=\"91db887\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4d9116c elementor-widget__width-initial wpr-logo-position-center elementor-widget elementor-widget-wpr-logo\" data-id=\"4d9116c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wpr-logo.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\n\t\t\t<div class=\"wpr-logo elementor-clearfix\">\n\n\t\t\t\t\t\t\t\t<picture class=\"wpr-logo-image\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/nbc-ev.de\/wp-content\/uploads\/2023\/09\/logo-1.png\" alt=\"\">\n\n\t\t\t\t\t\t\t\t\t<\/picture>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-14c8387\" data-id=\"14c8387\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-873f56f elementor-widget elementor-widget-elementskit-heading\" data-id=\"873f56f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--title elementskit-section-title\">Deutscher Basketball Bund U10 Kreisliga<\/h2>\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p>Duis aute irure dolor in reprehenderit in <br \/>voluptate velit esse cillum dolore eu <br \/>fugiat nulla pariatur.<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f1bffb elementor-align-left elementor-widget elementor-widget-elementskit-button\" data-id=\"1f1bffb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\t\t<div class=\"ekit-btn-wraper\">\n\t\t\t\t\t\t\t<a href=\"#\" class=\"elementskit-btn  whitespace--normal\" id=\"\">\n\t\t\t\t\tTo the tables<i class=\"fas fa-arrow-circle-right\"><\/i>\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e0287a1 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"e0287a1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ba669b9\" data-id=\"ba669b9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>U10mix Kreisliga Mike Trainer Mike Trainer 1980 Erwerb der Trainerlizenz f\u00fcr Basketball C-Leistungssport und regelm\u00e4\u00dfig Fortbildungen besucht, um die Lizenz und das Trainerwissen aktuell zu halten. Bereits 1979 die Ausbildung f\u00fcr die Schiedsrichterlizenz (LSD) absolviert. Anfangs noch als aktiver Spieler und Spielertrainer eingesetzt und sp\u00e4ter dann ohne Unterbrechung als Trainer f\u00fcr Herren und Damen sowie im gesamten Jugendbereich t\u00e4tig. In den letzten Jahren nur noch im Jugendbereich engagiert und einige Bayerische Meistertitel errungen. Viele Jugendcamps f\u00fcr den Bayerischen Basketballverband geleitet und auch einige Spieler entwickelt, die es bis in die Bundesliga und auch Nationalmannschaft geschafft haben. Phone:+49 1607961423 Email:mike@nbc-ev.de Martina Trainerin Martina Trainerin Nach einer aktiven und erfolgreichen Spielerkarriere bin ich seit vielen Jahren als Trainerin (C-Leistungstrainerin\/ \u00dcbungsleiterin seit 2000) ehrenamtlich t\u00e4tig, seit 2017 beim NBC. Des Weiteren habe ich langj\u00e4hrige Erfahrung als Schiedsrichterin (C-Lizenz). Mein Interesse gilt vor allem dem Jugendbereich, Anfangs trainierte ich ein U16 weiblich-Team, danach widmete ich mich \u2013bis auf zwei Saisons mit einem U14-Team -fast ausschlie\u00dflich der Altersklasse U12 (also 11Jahre und j\u00fcnger), da hier meiner Meinung nach der \u201eGrundstein\u201c gelegt wird, menschlich, sozial und auch spielerisch-spieltechnisch. Kinder f\u00fcr diesen tollen Sport zu begeistern und sich mit Freude und Spa\u00df weiter zu entwickeln, steht hierbei f\u00fcr mich im Vordergrund. Phone:+491577 3951388 Email:martina@nbc-ev.de U10 Ausbildungszeiten In den H\u00e4nden von engagierten U10-Trainern bei NBC eV werden diese jungen Spielerinnen und Spieler zu den zuk\u00fcnftigen S\u00e4ulen des Basketballs geformt Trainingszeiten DIENSTAGS UND DONNERSTAGS ZEIT : 16:00 &#8211; 18:00 HALLE D\u00fcrer Gymnasium,Sielstr. 17, 90429 Nuremberg Deutscher Basketball Bund U10 Kreisliga Duis aute irure dolor in reprehenderit in voluptate velit esse cillum dolore eu fugiat nulla pariatur. Zu den Tabellen<\/p>","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"_eb_attr":"","footnotes":""},"class_list":["post-1927","page","type-page","status-publish","hentry"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"Mike","author_link":"https:\/\/nbc-ev.de\/en\/author\/mike\/"},"rttpg_comment":0,"rttpg_category":null,"rttpg_excerpt":"U10mix Kreisliga Mike Trainer Mike Trainer 1980 Erwerb der Trainerlizenz f\u00fcr Basketball C-Leistungssport und regelm\u00e4\u00dfig Fortbildungen besucht, um die Lizenz und das Trainerwissen aktuell zu halten. Bereits 1979 die Ausbildung f\u00fcr die Schiedsrichterlizenz (LSD) absolviert. Anfangs noch als aktiver Spieler und Spielertrainer eingesetzt und sp\u00e4ter dann ohne Unterbrechung als Trainer f\u00fcr Herren und Damen sowie&hellip;","_links":{"self":[{"href":"https:\/\/nbc-ev.de\/en\/wp-json\/wp\/v2\/pages\/1927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nbc-ev.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nbc-ev.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nbc-ev.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nbc-ev.de\/en\/wp-json\/wp\/v2\/comments?post=1927"}],"version-history":[{"count":84,"href":"https:\/\/nbc-ev.de\/en\/wp-json\/wp\/v2\/pages\/1927\/revisions"}],"predecessor-version":[{"id":7437,"href":"https:\/\/nbc-ev.de\/en\/wp-json\/wp\/v2\/pages\/1927\/revisions\/7437"}],"wp:attachment":[{"href":"https:\/\/nbc-ev.de\/en\/wp-json\/wp\/v2\/media?parent=1927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}